{"id":13691,"date":"2022-05-17T18:05:59","date_gmt":"2022-05-17T16:05:59","guid":{"rendered":"https:\/\/www.f-dgs.com\/product\/senza-categoria\/cryogen-30-ra-generatore-di-azoto-liquido-n2\/"},"modified":"2022-05-17T18:05:59","modified_gmt":"2022-05-17T16:05:59","slug":"cryogen-30-ra-generatore-di-azoto-liquido-n2","status":"publish","type":"product","link":"https:\/\/www.f-dgs.com\/it\/product\/generatore-di-azoto-liquido\/cryogen-30-ra-generatore-di-azoto-liquido-n2\/","title":{"rendered":"CRYOGEN.30-RA Generatore di azoto liquido N2"},"content":{"rendered":"<p class=\"p1\">CRYOGEN.30-RA \u00e8 il generatore di N2 liquido <strong>&#8220;raffreddato ad aria&#8221;<\/strong> di F-DGSi.<\/p>\n<p class=\"p1\">Utilizzando un affidabile progetto di &#8220;crio-frigorifero&#8221; con tecnologia a testa fredda e compressore di elio, l&#8217;azoto gassoso viene poi prodotto con la tecnologia PSA e raffreddato a 77K (-196\u00b0C) per produrre azoto liquido.<\/p>\n<p class=\"p1\">I generatori sono controllati utilizzando la pi\u00f9 recente tecnologia HMI touch screen per visualizzare il processo in tempo reale, mostrando il livello di liquido del dewar, la produzione di azoto PSA e fornendo un sistema completamente automatizzato con la semplice pressione di un pulsante e l&#8217;accesso remoto per il controllo diagnostico.<\/p>\n<p class=\"p1\">L&#8217;azoto liquido pu\u00f2 essere erogato utilizzando un tubo isolato sotto vuoto di 1,5 metri. Le ventole di raffreddamento integrate possono funzionare con raffreddamento ad aria fino a una temperatura ambiente di +35\u00b0C, rendendolo adatto a operare ovunque nel mondo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CRYOGEN.30-RA \u00e8 il generatore di N2 liquido &#8220;raffreddato ad aria&#8221; di F-DGSi. Utilizzando un affidabile progetto di &#8220;crio-frigorifero&#8221; con tecnologia a testa fredda e compressore di elio, l&#8217;azoto gassoso viene poi prodotto con la tecnologia PSA e raffreddato a 77K (-196\u00b0C) per produrre azoto liquido. I generatori sono controllati utilizzando la pi\u00f9 recente tecnologia HMI [&hellip;]<\/p>\n","protected":false},"featured_media":13692,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[304],"product_tag":[],"class_list":{"0":"post-13691","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-generatore-di-azoto-liquido","8":"first","9":"instock","10":"shipping-taxable","11":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.f-dgs.com\/it\/wp-json\/wp\/v2\/product\/13691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.f-dgs.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.f-dgs.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.f-dgs.com\/it\/wp-json\/wp\/v2\/comments?post=13691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.f-dgs.com\/it\/wp-json\/wp\/v2\/media\/13692"}],"wp:attachment":[{"href":"https:\/\/www.f-dgs.com\/it\/wp-json\/wp\/v2\/media?parent=13691"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.f-dgs.com\/it\/wp-json\/wp\/v2\/product_cat?post=13691"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.f-dgs.com\/it\/wp-json\/wp\/v2\/product_tag?post=13691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}